{"id":453,"date":"2018-05-02T22:27:47","date_gmt":"2018-05-02T20:27:47","guid":{"rendered":"http:\/\/adepublicite.fr\/?page_id=453"},"modified":"2021-01-04T11:42:49","modified_gmt":"2021-01-04T10:42:49","slug":"dessous-de-verre","status":"publish","type":"page","link":"https:\/\/adepublicite.fr\/en\/plv-de-table\/dessous-de-verre\/","title":{"rendered":"Under glass"},"content":{"rendered":"<table style=\"width: 100%;\">\n<tbody>\n<tr>\n<td style=\"width: 75%;\">\n<h2>Description<\/h2>\n<p>Essential tools of work, why not to use under durable glasses?<\/p>\n<p>A solution to make you stand out with unique under glasses, seen nowhere else.<\/p>\n<p>Important and qualitative visual impact, play on its originality.<\/td>\n<td style=\"text-align: center; vertical-align: top;\"><div id=\"metaslider-id-285\" style=\"max-width: 700px;\" class=\"ml-slider-3-110-0 metaslider metaslider-flex metaslider-285 ml-slider ms-theme-default nav-hidden\" role=\"region\" aria-label=\"Dessous de verre\" data-height=\"300\" data-width=\"700\">\n    <div id=\"metaslider_container_285\">\n        <div id=\"metaslider_285\">\n            <ul class='slides'>\n                <li style=\"display: block; width: 100%;\" class=\"slide-286 ms-image \" aria-roledescription=\"slide\" data-date=\"2018-05-02 21:53:14\" data-filename=\"dessous_verre_2.jpg\" data-slide-type=\"image\"><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/adepublicite.fr\/wp-content\/uploads\/2018\/05\/dessous_verre_2.jpg\" class=\"slider-285 slide-286 msDefaultImage\" alt=\"\" rel=\"\" title=\"dessous_verre_2\" srcset=\"https:\/\/adepublicite.fr\/wp-content\/uploads\/2018\/05\/dessous_verre_2.jpg 500w, https:\/\/adepublicite.fr\/wp-content\/uploads\/2018\/05\/dessous_verre_2-150x150.jpg 150w, https:\/\/adepublicite.fr\/wp-content\/uploads\/2018\/05\/dessous_verre_2-300x300.jpg 300w, https:\/\/adepublicite.fr\/wp-content\/uploads\/2018\/05\/dessous_verre_2-365x365.jpg 365w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/li>\n                <li style=\"display: none; width: 100%;\" class=\"slide-288 ms-image \" aria-roledescription=\"slide\" data-date=\"2018-05-02 21:53:14\" data-filename=\"dessous_verre_3.jpg\" data-slide-type=\"image\"><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/adepublicite.fr\/wp-content\/uploads\/2018\/05\/dessous_verre_3.jpg\" class=\"slider-285 slide-288 msDefaultImage\" alt=\"\" rel=\"\" title=\"dessous_verre_3\" srcset=\"https:\/\/adepublicite.fr\/wp-content\/uploads\/2018\/05\/dessous_verre_3.jpg 500w, https:\/\/adepublicite.fr\/wp-content\/uploads\/2018\/05\/dessous_verre_3-150x150.jpg 150w, https:\/\/adepublicite.fr\/wp-content\/uploads\/2018\/05\/dessous_verre_3-300x300.jpg 300w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/li>\n                <li style=\"display: none; width: 100%;\" class=\"slide-287 ms-image \" aria-roledescription=\"slide\" data-date=\"2018-05-02 21:53:14\" data-filename=\"dessous_verre_1.jpg\" data-slide-type=\"image\"><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/adepublicite.fr\/wp-content\/uploads\/2018\/05\/dessous_verre_1.jpg\" class=\"slider-285 slide-287 msDefaultImage\" alt=\"\" rel=\"\" title=\"dessous_verre_1\" srcset=\"https:\/\/adepublicite.fr\/wp-content\/uploads\/2018\/05\/dessous_verre_1.jpg 500w, https:\/\/adepublicite.fr\/wp-content\/uploads\/2018\/05\/dessous_verre_1-150x150.jpg 150w, https:\/\/adepublicite.fr\/wp-content\/uploads\/2018\/05\/dessous_verre_1-300x300.jpg 300w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/li>\n                <li style=\"display: none; width: 100%;\" class=\"slide-289 ms-image \" aria-roledescription=\"slide\" data-date=\"2018-05-02 21:53:16\" data-filename=\"dessous_verre_4.jpg\" data-slide-type=\"image\"><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/adepublicite.fr\/wp-content\/uploads\/2018\/05\/dessous_verre_4.jpg\" class=\"slider-285 slide-289 msDefaultImage\" alt=\"\" rel=\"\" title=\"dessous_verre_4\" srcset=\"https:\/\/adepublicite.fr\/wp-content\/uploads\/2018\/05\/dessous_verre_4.jpg 500w, https:\/\/adepublicite.fr\/wp-content\/uploads\/2018\/05\/dessous_verre_4-150x150.jpg 150w, https:\/\/adepublicite.fr\/wp-content\/uploads\/2018\/05\/dessous_verre_4-300x300.jpg 300w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/li>\n            <\/ul>\n        <\/div>\n        \n    <\/div>\n<\/div><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<h2>Technical description<\/h2>\n<p><strong>Support:<\/strong> plexi, PVC, dibond, wood, cork<\/p>\n<p><strong>Printing:<\/strong> silkscreen or digital<\/p>\n<p><strong>Standard formats:<\/strong> 9cm in diameter (other sizes possibles)<\/p>\n<p><strong>Finishies and options :<\/strong> cut in shape (other options on demand)<\/p>\n<p><strong>Packaging:<\/strong> in batch under film<\/p>\n<p><strong>Origin : <\/strong>in our permises in Is\u00e8re (France)<\/p>\n<p>Want to know more about our slate manufacturing techniques? Visit the\u00a0<a href=\"https:\/\/adepublicite.fr\/en\/savoir-faire\/\">know-how<\/a>\u00a0page or\u00a0<a href=\"https:\/\/adepublicite.fr\/en\/contact\/\">come and meet us<\/a>!<\/p>\n<h2>Prices<\/h2>\n<p>Our prices depend on your personalization criteria (the size of the blackboard, the number of colors to print, the type of framing, if necessary the retouching your files, the quantity \u2026 see our\u00a0<a href=\"https:\/\/adepublicite.fr\/en\/savoir-faire\/\">know-how<\/a>\u00a0for more explanations), and are therefore exclusively on estimate.<\/p>\n<h2>Similar products<\/h2>\n<table style=\"width: 100%;\">\n<tbody>\n<tr>\n<td style=\"width: 25%; text-align: center;\"><\/td>\n<td style=\"width: 25%; text-align: center;\"><\/td>\n<td style=\"width: 25%; text-align: center;\"><\/td>\n<td style=\"width: 25%; text-align: center;\"><\/td>\n<\/tr>\n<tr>\n<td style=\"width: 25%; text-align: center;\"><\/td>\n<td style=\"width: 25%; text-align: center;\"><\/td>\n<td style=\"width: 25%; text-align: center;\"><\/td>\n<td style=\"width: 25%; text-align: center;\"><\/td>\n<\/tr>\n<tr>\n<td style=\"width: 25%; text-align: center;\"><\/td>\n<td style=\"width: 25%; text-align: center;\"><\/td>\n<td style=\"width: 25%; text-align: center;\"><\/td>\n<td style=\"width: 25%; text-align: center;\"><\/td>\n<\/tr>\n<tr>\n<td style=\"width: 25%; text-align: center;\"><\/td>\n<td style=\"width: 25%; text-align: center;\"><\/td>\n<td style=\"width: 25%; text-align: center;\"><\/td>\n<td style=\"width: 25%; text-align: center;\"><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n","protected":false},"excerpt":{"rendered":"<p>Description Essential tools of work, why not to use under durable glasses? A solution to make you stand out with unique under glasses, seen nowhere else. Important and qualitative visual impact, play on its originality. Technical description Support: plexi, PVC, &hellip; <a href=\"https:\/\/adepublicite.fr\/en\/plv-de-table\/dessous-de-verre\/\">Continued<\/a><\/p>\n","protected":false},"author":1,"featured_media":123,"parent":441,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"kt_blocks_editor_width":"","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"class_list":["post-453","page","type-page","status-publish","has-post-thumbnail","hentry"],"translation":{"provider":"WPGlobus","version":"3.0.2","language":"en","enabled_languages":["fr","en"],"languages":{"fr":{"title":true,"content":true,"excerpt":false},"en":{"title":true,"content":true,"excerpt":false}}},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Dessous de verre durables publicitaires personnalis\u00e9s sur mesure<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/adepublicite.fr\/plv-de-table\/dessous-de-verre\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Under glass - ADE Publicit\u00e9\" \/>\n<meta property=\"og:url\" content=\"https:\/\/adepublicite.fr\/plv-de-table\/dessous-de-verre\/\" \/>\n<meta property=\"og:site_name\" content=\"ADE Publicit\u00e9\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/adepublicite\/?ref=bookmarks\" \/>\n<meta property=\"article:modified_time\" content=\"2021-01-04T10:42:49+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/adepublicite.fr\/wp-content\/uploads\/2018\/05\/dessous_verre_2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"500\" \/>\n\t<meta property=\"og:image:height\" content=\"500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/adepublicite.fr\\\/plv-de-table\\\/dessous-de-verre\\\/\",\"url\":\"https:\\\/\\\/adepublicite.fr\\\/plv-de-table\\\/dessous-de-verre\\\/\",\"name\":\"Dessous de verre durables publicitaires personnalis\u00e9s sur mesure\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/adepublicite.fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/adepublicite.fr\\\/plv-de-table\\\/dessous-de-verre\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/adepublicite.fr\\\/plv-de-table\\\/dessous-de-verre\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/adepublicite.fr\\\/wp-content\\\/uploads\\\/2018\\\/05\\\/dessous_verre_2.jpg\",\"datePublished\":\"2018-05-02T20:27:47+00:00\",\"dateModified\":\"2021-01-04T10:42:49+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/adepublicite.fr\\\/plv-de-table\\\/dessous-de-verre\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/adepublicite.fr\\\/plv-de-table\\\/dessous-de-verre\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/adepublicite.fr\\\/plv-de-table\\\/dessous-de-verre\\\/#primaryimage\",\"url\":\"https:\\\/\\\/adepublicite.fr\\\/wp-content\\\/uploads\\\/2018\\\/05\\\/dessous_verre_2.jpg\",\"contentUrl\":\"https:\\\/\\\/adepublicite.fr\\\/wp-content\\\/uploads\\\/2018\\\/05\\\/dessous_verre_2.jpg\",\"width\":500,\"height\":500},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/adepublicite.fr\\\/plv-de-table\\\/dessous-de-verre\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/adepublicite.fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"PLV de table\",\"item\":\"https:\\\/\\\/adepublicite.fr\\\/plv-de-table\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Dessous de verre\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/adepublicite.fr\\\/#website\",\"url\":\"https:\\\/\\\/adepublicite.fr\\\/\",\"name\":\"ADE Publicit\u00e9\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/adepublicite.fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/adepublicite.fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/adepublicite.fr\\\/#organization\",\"name\":\"ADE Publicit\u00e9\",\"url\":\"https:\\\/\\\/adepublicite.fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/adepublicite.fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/adepublicite.fr\\\/wp-content\\\/uploads\\\/2018\\\/05\\\/FAVICON.png\",\"contentUrl\":\"https:\\\/\\\/adepublicite.fr\\\/wp-content\\\/uploads\\\/2018\\\/05\\\/FAVICON.png\",\"width\":512,\"height\":512,\"caption\":\"ADE Publicit\u00e9\"},\"image\":{\"@id\":\"https:\\\/\\\/adepublicite.fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/adepublicite\\\/?ref=bookmarks\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/ade-publicit\u00e9\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Dessous de verre durables publicitaires personnalis\u00e9s sur mesure","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/adepublicite.fr\/plv-de-table\/dessous-de-verre\/","og_locale":"en_US","og_type":"article","og_title":"Under glass - ADE Publicit\u00e9","og_url":"https:\/\/adepublicite.fr\/plv-de-table\/dessous-de-verre\/","og_site_name":"ADE Publicit\u00e9","article_publisher":"https:\/\/www.facebook.com\/adepublicite\/?ref=bookmarks","article_modified_time":"2021-01-04T10:42:49+00:00","og_image":[{"width":500,"height":500,"url":"https:\/\/adepublicite.fr\/wp-content\/uploads\/2018\/05\/dessous_verre_2.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/adepublicite.fr\/plv-de-table\/dessous-de-verre\/","url":"https:\/\/adepublicite.fr\/plv-de-table\/dessous-de-verre\/","name":"Dessous de verre durables publicitaires personnalis\u00e9s sur mesure","isPartOf":{"@id":"https:\/\/adepublicite.fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/adepublicite.fr\/plv-de-table\/dessous-de-verre\/#primaryimage"},"image":{"@id":"https:\/\/adepublicite.fr\/plv-de-table\/dessous-de-verre\/#primaryimage"},"thumbnailUrl":"https:\/\/adepublicite.fr\/wp-content\/uploads\/2018\/05\/dessous_verre_2.jpg","datePublished":"2018-05-02T20:27:47+00:00","dateModified":"2021-01-04T10:42:49+00:00","breadcrumb":{"@id":"https:\/\/adepublicite.fr\/plv-de-table\/dessous-de-verre\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/adepublicite.fr\/plv-de-table\/dessous-de-verre\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/adepublicite.fr\/plv-de-table\/dessous-de-verre\/#primaryimage","url":"https:\/\/adepublicite.fr\/wp-content\/uploads\/2018\/05\/dessous_verre_2.jpg","contentUrl":"https:\/\/adepublicite.fr\/wp-content\/uploads\/2018\/05\/dessous_verre_2.jpg","width":500,"height":500},{"@type":"BreadcrumbList","@id":"https:\/\/adepublicite.fr\/plv-de-table\/dessous-de-verre\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/adepublicite.fr\/"},{"@type":"ListItem","position":2,"name":"PLV de table","item":"https:\/\/adepublicite.fr\/plv-de-table\/"},{"@type":"ListItem","position":3,"name":"Dessous de verre"}]},{"@type":"WebSite","@id":"https:\/\/adepublicite.fr\/#website","url":"https:\/\/adepublicite.fr\/","name":"ADE Publicit\u00e9","description":"","publisher":{"@id":"https:\/\/adepublicite.fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/adepublicite.fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/adepublicite.fr\/#organization","name":"ADE Publicit\u00e9","url":"https:\/\/adepublicite.fr\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/adepublicite.fr\/#\/schema\/logo\/image\/","url":"https:\/\/adepublicite.fr\/wp-content\/uploads\/2018\/05\/FAVICON.png","contentUrl":"https:\/\/adepublicite.fr\/wp-content\/uploads\/2018\/05\/FAVICON.png","width":512,"height":512,"caption":"ADE Publicit\u00e9"},"image":{"@id":"https:\/\/adepublicite.fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/adepublicite\/?ref=bookmarks","https:\/\/www.linkedin.com\/company\/ade-publicit\u00e9\/"]}]}},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/adepublicite.fr\/en\/wp-json\/wp\/v2\/pages\/453","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/adepublicite.fr\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/adepublicite.fr\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/adepublicite.fr\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/adepublicite.fr\/en\/wp-json\/wp\/v2\/comments?post=453"}],"version-history":[{"count":11,"href":"https:\/\/adepublicite.fr\/en\/wp-json\/wp\/v2\/pages\/453\/revisions"}],"predecessor-version":[{"id":3443,"href":"https:\/\/adepublicite.fr\/en\/wp-json\/wp\/v2\/pages\/453\/revisions\/3443"}],"up":[{"embeddable":true,"href":"https:\/\/adepublicite.fr\/en\/wp-json\/wp\/v2\/pages\/441"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/adepublicite.fr\/en\/wp-json\/wp\/v2\/media\/123"}],"wp:attachment":[{"href":"https:\/\/adepublicite.fr\/en\/wp-json\/wp\/v2\/media?parent=453"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}